{"id":8495,"date":"2024-07-27T15:06:59","date_gmt":"2024-07-27T18:06:59","guid":{"rendered":"https:\/\/aldiachaco.com.ar\/?p=8495"},"modified":"2024-07-27T15:06:59","modified_gmt":"2024-07-27T18:06:59","slug":"argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos","status":"publish","type":"post","link":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/","title":{"rendered":"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos"},"content":{"rendered":"<p>La selecci\u00f3n argentina Sub 23 se impuso con autoridad ante Irak, logrando una victoria por 3-1 en la segunda fecha del Grupo B del torneo masculino de f\u00fatbol de los Juegos Ol\u00edmpicos de Par\u00eds 2024. Con goles de Thiago Almada, Luciano Gondou y Equi Fern\u00e1ndez, la Albiceleste se posiciona como l\u00edder del grupo y se perfila para avanzar a los cuartos de final.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8497 aligncenter\" src=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/597-Argentina-300x225.jpg\" alt=\"\" width=\"476\" height=\"357\" srcset=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/597-Argentina-300x225.jpg 300w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/597-Argentina-628x470.jpg 628w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/597-Argentina-600x449.jpg 600w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/597-Argentina.jpg 720w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/p>\n<p>El partido comenz\u00f3 con dominio argentino y fue Thiago Almada quien abri\u00f3 el marcador. Sin embargo, Irak logr\u00f3 empatar antes del final del primer tiempo con un cabezazo de Aymen Hussein. A pesar de la igualdad temporal, el equipo dirigido por Javier Mascherano supo mantener la calma y despleg\u00f3 un juego contundente en el segundo tiempo.<\/p>\n<p>Al inicio del complemento, un centro de Kevin Zen\u00f3n, quien hab\u00eda ingresado recientemente, fue capitalizado por Luciano Gondou para poner nuevamente en ventaja a la Albiceleste. Minutos despu\u00e9s, Equi Fern\u00e1ndez sell\u00f3 la victoria con un espectacular zurdazo, culminando una brillante jugada colectiva.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8499 aligncenter\" src=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/595-Argentina-300x177.jpg\" alt=\"\" width=\"514\" height=\"303\" srcset=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/595-Argentina-300x177.jpg 300w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/595-Argentina-1024x604.jpg 1024w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/595-Argentina-768x453.jpg 768w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/595-Argentina-780x460.jpg 780w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/595-Argentina-600x354.jpg 600w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/595-Argentina.jpg 1289w\" sizes=\"auto, (max-width: 514px) 100vw, 514px\" \/><\/p>\n<p>Con esta victoria, Argentina suma puntos cruciales y solo necesita un empate en su pr\u00f3ximo encuentro contra Ucrania para asegurar su lugar en los cuartos de final. El partido decisivo se jugar\u00e1 el pr\u00f3ximo martes en Niza a las 12 horas (hora argentina). La selecci\u00f3n ucraniana llega tras vencer 2-1 a los africanos, lo que convierte al pr\u00f3ximo enfrentamiento en un duelo decisivo para ambos equipos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La selecci\u00f3n argentina Sub 23 se impuso con autoridad ante Irak, logrando una victoria por 3-1 en la segunda fecha del Grupo B del torneo masculino de f\u00fatbol de los Juegos Ol\u00edmpicos de Par\u00eds 2024. Con goles de Thiago Almada, Luciano Gondou y Equi Fern\u00e1ndez, la Albiceleste se posiciona como l\u00edder del grupo y se &hellip;<\/p>\n","protected":false},"author":1,"featured_media":8498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[72,94],"tags":[200],"class_list":["post-8495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-nacionales","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos | Al Dia Chaco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos | Al Dia Chaco\" \/>\n<meta property=\"og:description\" content=\"La selecci\u00f3n argentina Sub 23 se impuso con autoridad ante Irak, logrando una victoria por 3-1 en la segunda fecha del Grupo B del torneo masculino de f\u00fatbol de los Juegos Ol\u00edmpicos de Par\u00eds 2024. Con goles de Thiago Almada, Luciano Gondou y Equi Fern\u00e1ndez, la Albiceleste se posiciona como l\u00edder del grupo y se &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Al Dia Chaco\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-27T18:06:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/596-Argentina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1290\" \/>\n\t<meta property=\"og:image:height\" content=\"759\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aldiachaco.com.ar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aldiachaco.com.ar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/\"},\"author\":{\"name\":\"aldiachaco.com.ar\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/person\\\/80113835e512ba580e79a945932487f5\"},\"headline\":\"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos\",\"datePublished\":\"2024-07-27T18:06:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/\"},\"wordCount\":256,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/596-Argentina.jpg\",\"keywords\":[\"Destacada\"],\"articleSection\":[\"Deportes\",\"Nacionales\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/\",\"name\":\"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos | Al Dia Chaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/596-Argentina.jpg\",\"datePublished\":\"2024-07-27T18:06:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/596-Argentina.jpg\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/596-Argentina.jpg\",\"width\":1290,\"height\":759},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/27\\\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\",\"name\":\"Al Dia Chaco\",\"description\":\"Noticias del Chaco y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\"},\"alternateName\":\"Al D\u00eda Chaco\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aldiachaco.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\",\"name\":\"Al Dia Chaco\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AL-DIA-CHACO-L@2x.png\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AL-DIA-CHACO-L@2x.png\",\"width\":232,\"height\":60,\"caption\":\"Al Dia Chaco\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/person\\\/80113835e512ba580e79a945932487f5\",\"name\":\"aldiachaco.com.ar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"caption\":\"aldiachaco.com.ar\"},\"sameAs\":[\"https:\\\/\\\/aldiachaco.com.ar\"],\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/author\\\/lime-camel-884546-hostingersite-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos | Al Dia Chaco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/","og_locale":"es_ES","og_type":"article","og_title":"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos | Al Dia Chaco","og_description":"La selecci\u00f3n argentina Sub 23 se impuso con autoridad ante Irak, logrando una victoria por 3-1 en la segunda fecha del Grupo B del torneo masculino de f\u00fatbol de los Juegos Ol\u00edmpicos de Par\u00eds 2024. Con goles de Thiago Almada, Luciano Gondou y Equi Fern\u00e1ndez, la Albiceleste se posiciona como l\u00edder del grupo y se &hellip;","og_url":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/","og_site_name":"Al Dia Chaco","article_published_time":"2024-07-27T18:06:59+00:00","og_image":[{"width":1290,"height":759,"url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/596-Argentina.jpg","type":"image\/jpeg"}],"author":"aldiachaco.com.ar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aldiachaco.com.ar","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/#article","isPartOf":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/"},"author":{"name":"aldiachaco.com.ar","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/person\/80113835e512ba580e79a945932487f5"},"headline":"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos","datePublished":"2024-07-27T18:06:59+00:00","mainEntityOfPage":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/"},"wordCount":256,"commentCount":0,"publisher":{"@id":"https:\/\/aldiachaco.com.ar\/#organization"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/#primaryimage"},"thumbnailUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/596-Argentina.jpg","keywords":["Destacada"],"articleSection":["Deportes","Nacionales"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/","url":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/","name":"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos | Al Dia Chaco","isPartOf":{"@id":"https:\/\/aldiachaco.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/#primaryimage"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/#primaryimage"},"thumbnailUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/596-Argentina.jpg","datePublished":"2024-07-27T18:06:59+00:00","breadcrumb":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/#primaryimage","url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/596-Argentina.jpg","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/596-Argentina.jpg","width":1290,"height":759},{"@type":"BreadcrumbList","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/27\/argentina-derroto-3-a-1-a-irak-y-quedo-a-un-paso-de-los-cuartos-en-los-juegos-olimpicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aldiachaco.com.ar\/"},{"@type":"ListItem","position":2,"name":"Argentina derrot\u00f3 3 a 1 a Irak y qued\u00f3 a un paso de los cuartos en los Juegos Ol\u00edmpicos"}]},{"@type":"WebSite","@id":"https:\/\/aldiachaco.com.ar\/#website","url":"https:\/\/aldiachaco.com.ar\/","name":"Al Dia Chaco","description":"Noticias del Chaco y el mundo","publisher":{"@id":"https:\/\/aldiachaco.com.ar\/#organization"},"alternateName":"Al D\u00eda Chaco","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aldiachaco.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/aldiachaco.com.ar\/#organization","name":"Al Dia Chaco","url":"https:\/\/aldiachaco.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2017\/11\/AL-DIA-CHACO-L@2x.png","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2017\/11\/AL-DIA-CHACO-L@2x.png","width":232,"height":60,"caption":"Al Dia Chaco"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/person\/80113835e512ba580e79a945932487f5","name":"aldiachaco.com.ar","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","url":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","caption":"aldiachaco.com.ar"},"sameAs":["https:\/\/aldiachaco.com.ar"],"url":"https:\/\/aldiachaco.com.ar\/index.php\/author\/lime-camel-884546-hostingersite-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/596-Argentina.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=8495"}],"version-history":[{"count":1,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8495\/revisions"}],"predecessor-version":[{"id":8500,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8495\/revisions\/8500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/media\/8498"}],"wp:attachment":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=8495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=8495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=8495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}