{"id":8365,"date":"2024-07-23T17:28:56","date_gmt":"2024-07-23T20:28:56","guid":{"rendered":"https:\/\/aldiachaco.com.ar\/?p=8365"},"modified":"2024-07-23T17:35:10","modified_gmt":"2024-07-23T20:35:10","slug":"dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad","status":"publish","type":"post","link":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/","title":{"rendered":"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad"},"content":{"rendered":"<p>En un r\u00e1pido accionar policial, un joven de 18 a\u00f1os identificado como A.K.D., alias &#8220;Lilo&#8221;, fue detenido tras un violento intento de robo en una panader\u00eda ubicada en avenida Edison al 1300. La fiscal\u00eda en turno dispuso que el acusado sea notificado en la causa por &#8220;Supuesto Robo en Grado de Tentativa&#8221;.<\/p>\n<div class=\"ose-facebook ose-uid-46d41416115981be77e537795fa49642 ose-embedpress-responsive\" style=\"width:600px; height:550px; max-height:550px; max-width:100%; display:inline-block;\" data-embed-type=\"Facebook\"><div id=\"fb-root\"><\/div><script async=\"1\" defer=\"1\" crossorigin=\"anonymous\" src=\"https:\/\/connect.facebook.net\/pt_PT\/sdk.js#xfbml=1&amp;version=v25.0\"><\/script><div class=\"fb-video\" data-href=\"https:\/\/www.facebook.com\/aldiachaco\/videos\/1493591811362466\" data-width=\"600\"><blockquote cite=\"https:\/\/www.facebook.com\/aldiachaco\/videos\/1493591811362466\/\" class=\"fb-xfbml-parse-ignore\"><a href=\"https:\/\/www.facebook.com\/aldiachaco\/videos\/1493591811362466\/\"><\/a><p>DRAM\u00c1TICO INTENTO DE ROBO A UNA PANADER\u00cdA: DETIENEN A \u201cLILO\u201d GRACIAS A C\u00c1MARAS DE SEGURIDADEn un r\u00e1pido accionar policial, un joven de 18 a\u00f1os identificado como A.K.D., alias &quot;Lilo&quot;, fue detenido tras un violento intento de robo en una panader\u00eda ubicada en avenida Edison al 1300. La fiscal\u00eda en turno dispuso que el acusado sea notificado en la causa por &quot;Supuesto Robo en Grado de Tentativa&quot;.<\/p>Posted by <a href=\"https:\/\/www.facebook.com\/aldiachaco\">Al Dia Chaco<\/a> on Tuesday, July 23, 2024<\/blockquote><\/div><\/div>\n<p>El incidente ocurri\u00f3 cuando N.N.A., una empleada de 34 a\u00f1os de la panader\u00eda, se encontraba en su jornada laboral y fue sorprendida por &#8220;Lilo&#8221;, quien intent\u00f3 sustraerle dinero. Al no conseguir su objetivo, el joven se dio a la fuga, no sin antes lastimar a la empleada y causar da\u00f1os en el vidrio del local.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8368 aligncenter\" src=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/552-Panaderia-300x169.webp\" alt=\"\" width=\"570\" height=\"321\" srcset=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/552-Panaderia-300x169.webp 300w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/552-Panaderia-768x434.webp 768w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/552-Panaderia-390x220.webp 390w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/552-Panaderia-780x440.webp 780w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/552-Panaderia-600x339.webp 600w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/552-Panaderia.webp 850w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/p>\n<p>Las c\u00e1maras de seguridad del establecimiento jugaron un papel crucial en la identificaci\u00f3n del sospechoso. El personal investigativo realiz\u00f3 un an\u00e1lisis detallado del material f\u00edlmico, lo que permiti\u00f3 identificar y localizar a &#8220;Lilo&#8221;. Este martes a las 13:30 horas, las autoridades lograron detener al joven, quien intent\u00f3 escapar al percatarse de la presencia policial, pero fue r\u00e1pidamente alcanzado.<\/p>\n<p>Posteriormente, &#8220;Lilo&#8221; fue trasladado al Departamento de Medicina Legal y luego a la comisar\u00eda 7ma Metropolitana, donde qued\u00f3 a disposici\u00f3n de la Fiscal\u00eda Penal interviniente. El fiscal en turno determin\u00f3 que el joven sea notificado oficialmente por el delito de &#8220;Supuesto Robo en Grado de Tentativa&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un r\u00e1pido accionar policial, un joven de 18 a\u00f1os identificado como A.K.D., alias &#8220;Lilo&#8221;, fue detenido tras un violento intento de robo en una panader\u00eda ubicada en avenida Edison al 1300. La fiscal\u00eda en turno dispuso que el acusado sea notificado en la causa por &#8220;Supuesto Robo en Grado de Tentativa&#8221;. El incidente ocurri\u00f3 &hellip;<\/p>\n","protected":false},"author":1,"featured_media":8367,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[67,86,68],"tags":[200],"class_list":["post-8365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-policiales","category-resistencia","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad | Al Dia Chaco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad | Al Dia Chaco\" \/>\n<meta property=\"og:description\" content=\"En un r\u00e1pido accionar policial, un joven de 18 a\u00f1os identificado como A.K.D., alias &#8220;Lilo&#8221;, fue detenido tras un violento intento de robo en una panader\u00eda ubicada en avenida Edison al 1300. La fiscal\u00eda en turno dispuso que el acusado sea notificado en la causa por &#8220;Supuesto Robo en Grado de Tentativa&#8221;. El incidente ocurri\u00f3 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Al Dia Chaco\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-23T20:28:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T20:35:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/553-Panaderia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aldiachaco.com.ar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aldiachaco.com.ar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/\"},\"author\":{\"name\":\"aldiachaco.com.ar\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/person\\\/80113835e512ba580e79a945932487f5\"},\"headline\":\"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad\",\"datePublished\":\"2024-07-23T20:28:56+00:00\",\"dateModified\":\"2024-07-23T20:35:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/\"},\"wordCount\":252,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/553-Panaderia.jpg\",\"keywords\":[\"Destacada\"],\"articleSection\":[\"Chaco\",\"Policiales\",\"Resistencia\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/\",\"name\":\"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad | Al Dia Chaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/553-Panaderia.jpg\",\"datePublished\":\"2024-07-23T20:28:56+00:00\",\"dateModified\":\"2024-07-23T20:35:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/553-Panaderia.jpg\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/553-Panaderia.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/07\\\/23\\\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\",\"name\":\"Al Dia Chaco\",\"description\":\"Noticias del Chaco y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\"},\"alternateName\":\"Al D\u00eda Chaco\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aldiachaco.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\",\"name\":\"Al Dia Chaco\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AL-DIA-CHACO-L@2x.png\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AL-DIA-CHACO-L@2x.png\",\"width\":232,\"height\":60,\"caption\":\"Al Dia Chaco\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/person\\\/80113835e512ba580e79a945932487f5\",\"name\":\"aldiachaco.com.ar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"caption\":\"aldiachaco.com.ar\"},\"sameAs\":[\"https:\\\/\\\/aldiachaco.com.ar\"],\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/author\\\/lime-camel-884546-hostingersite-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad | Al Dia Chaco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/","og_locale":"es_ES","og_type":"article","og_title":"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad | Al Dia Chaco","og_description":"En un r\u00e1pido accionar policial, un joven de 18 a\u00f1os identificado como A.K.D., alias &#8220;Lilo&#8221;, fue detenido tras un violento intento de robo en una panader\u00eda ubicada en avenida Edison al 1300. La fiscal\u00eda en turno dispuso que el acusado sea notificado en la causa por &#8220;Supuesto Robo en Grado de Tentativa&#8221;. El incidente ocurri\u00f3 &hellip;","og_url":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/","og_site_name":"Al Dia Chaco","article_published_time":"2024-07-23T20:28:56+00:00","article_modified_time":"2024-07-23T20:35:10+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/553-Panaderia.jpg","type":"image\/jpeg"}],"author":"aldiachaco.com.ar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aldiachaco.com.ar","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/#article","isPartOf":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/"},"author":{"name":"aldiachaco.com.ar","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/person\/80113835e512ba580e79a945932487f5"},"headline":"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad","datePublished":"2024-07-23T20:28:56+00:00","dateModified":"2024-07-23T20:35:10+00:00","mainEntityOfPage":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/"},"wordCount":252,"commentCount":0,"publisher":{"@id":"https:\/\/aldiachaco.com.ar\/#organization"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/553-Panaderia.jpg","keywords":["Destacada"],"articleSection":["Chaco","Policiales","Resistencia"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/","url":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/","name":"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad | Al Dia Chaco","isPartOf":{"@id":"https:\/\/aldiachaco.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/#primaryimage"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/553-Panaderia.jpg","datePublished":"2024-07-23T20:28:56+00:00","dateModified":"2024-07-23T20:35:10+00:00","breadcrumb":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/#primaryimage","url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/553-Panaderia.jpg","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/553-Panaderia.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/07\/23\/dramatico-intento-de-robo-a-una-panaderia-detienen-a-lilo-gracias-a-camaras-de-seguridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aldiachaco.com.ar\/"},{"@type":"ListItem","position":2,"name":"Dram\u00e1tico intento de robo a una panader\u00eda: Detienen a \u201cLilo\u201d gracias a c\u00e1maras de seguridad"}]},{"@type":"WebSite","@id":"https:\/\/aldiachaco.com.ar\/#website","url":"https:\/\/aldiachaco.com.ar\/","name":"Al Dia Chaco","description":"Noticias del Chaco y el mundo","publisher":{"@id":"https:\/\/aldiachaco.com.ar\/#organization"},"alternateName":"Al D\u00eda Chaco","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aldiachaco.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/aldiachaco.com.ar\/#organization","name":"Al Dia Chaco","url":"https:\/\/aldiachaco.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2017\/11\/AL-DIA-CHACO-L@2x.png","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2017\/11\/AL-DIA-CHACO-L@2x.png","width":232,"height":60,"caption":"Al Dia Chaco"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/person\/80113835e512ba580e79a945932487f5","name":"aldiachaco.com.ar","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","url":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","caption":"aldiachaco.com.ar"},"sameAs":["https:\/\/aldiachaco.com.ar"],"url":"https:\/\/aldiachaco.com.ar\/index.php\/author\/lime-camel-884546-hostingersite-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/07\/553-Panaderia.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=8365"}],"version-history":[{"count":2,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8365\/revisions"}],"predecessor-version":[{"id":8370,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8365\/revisions\/8370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/media\/8367"}],"wp:attachment":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=8365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=8365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=8365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}