{"id":5763,"date":"2024-05-16T08:26:46","date_gmt":"2024-05-16T11:26:46","guid":{"rendered":"https:\/\/aldiachaco.com.ar\/?p=5763"},"modified":"2024-05-16T08:48:21","modified_gmt":"2024-05-16T11:48:21","slug":"no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta","status":"publish","type":"post","link":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/","title":{"rendered":"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta"},"content":{"rendered":"<p>Roberto Giordano\u00a0fue condenado en la tarde de este mi\u00e9rcoles a\u00a03 a\u00f1os de prisi\u00f3n\u00a0luego de aceptar su culpabilidad en un\u00a0juicio abreviado\u00a0donde se lo acusaba de\u00a0insolvencia fraudulenta. Es decir, esconder bienes adrede para que no sean embargados por la justicia. La sentencia fue firmada en la tarde de hoy por el juez\u00a0Jorge Alejandro Zabala. Es v\u00e1lido recordar que el peluquero tiene ya una sentencia previa a dos a\u00f1os por una causa similar. Ese expediente est\u00e1 esperando a\u00fan confirmaci\u00f3n de la\u00a0Corte Suprema de Justicia.<\/p>\n<p>La causa ten\u00eda una fuerte carga probatoria contra el otrora peluquero de las estrellas. En el expediente se acumularon\u00a0documentos y testimonios\u00a0que lo complicaban y mucho. Por esto, no tuvo m\u00e1s remedio que declararse culpable y evitar una pena mayor.<\/p>\n<p>\u201cLo que hizo Giordano fue, b\u00e1sicamente, crear una serie de empresas falsas y sellos de goma que puso a nombre de conocidos suyos, en su mayor\u00eda empleados sin capacidad financiera. Empresas que en realidad \u00e9l manejaba desde las sombras. Es decir, us\u00f3 testaferros.\u00a0El objetivo fue esconder en esas sociedades fantasmas 17 bienes para evitar perderlos, ya que la AFIP lo estaba investigando y \u00e9l lo sab\u00eda\u201d, explic\u00f3 una fuente en los tribunales del fuero penal econ\u00f3mico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5765 aligncenter\" src=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/79-Detenidos-300x169.avif\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/79-Detenidos-300x169.avif 300w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/79-Detenidos-768x432.avif 768w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/79-Detenidos-390x220.avif 390w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/79-Detenidos-780x439.avif 780w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/79-Detenidos-600x338.avif 600w, https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/79-Detenidos.avif 992w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Seg\u00fan la reconstrucci\u00f3n judicial, al verse acorralado por las requisas fiscales de la AFIP sobre su peluquer\u00eda, que ten\u00eda bajo la sociedad ASPIL S.A., Giordano habr\u00eda utilizado testaferros para crear empresas paralelas en las cuales \u00e9l no ten\u00eda ning\u00fan tipo de responsabilidad en los papeles, pero que segu\u00eda dirigiendo en la pr\u00e1ctica. A esas empresas, llamadas Nilamar S.A., Big Brands S.A., Arimis S.R.L. y Unidor S.R.L., entre otras, traslad\u00f3 personal y sobre todo, bienes.<\/p>\n<p>\u201cUna vez que hizo todo eso, la empresa que \u00e9l reconoc\u00eda como propia, ASPIL S.A., qued\u00f3 vac\u00eda, es decir, solo qued\u00f3 el cascar\u00f3n: sin empleados, sin bienes, sin absolutamente nada. Mientras tanto, segu\u00eda ah\u00ed acumulando deudas, no pagaba impuestos, evitaba abonar las cargas sociales. Si le hac\u00edan juicio, ya no ten\u00eda nada a su nombre, lo hab\u00eda pasado todo a las empresas truchas. Esa es la maniobra. La realidad es que es muy com\u00fan que se haga esto solo que \u00e9l lo llev\u00f3 al paroxismo\u201d, afirm\u00f3 una fuente que conoce los tribunales y, sobre todo, a Giordano.<\/p>\n<p>Para entender el complejo entramado que realiz\u00f3\u00a0Giordano, y que se\u00a0investig\u00f3 durante m\u00e1s de 6 a\u00f1os\u00a0hasta llegar a esta instancia de juicio abreviado, conviene repasar el\u00a0procesamiento\u00a0que sufri\u00f3 el peluquero el\u00a05 de junio del 2020, y en el que se explic\u00f3 detalladamente el delito.<\/p>\n<p>En total\u00a0fueron 17 los bienes que el peluquero pas\u00f3 de su empresa a las sociedades fantasmas manejadas por sus conocidos.\u00a0Lo hizo a trav\u00e9s de ventas a valores nulos, bajos o transferidos directamente a personas carentes de solvencia econ\u00f3mica. Luego los desapoderaba de sus bienes en detrimento de sus patrimonios.<\/p>\n<p>Cuando el peluquero tuvo la oportunidad de defenderse en indagatoria, desconoci\u00f3 esas maniobras. Dijo\u00a0que era un simple empleado.\u00a0Asegur\u00f3 que las empresas falsas lo hab\u00edan contratado a \u00e9l y que no ten\u00eda ning\u00fan tipo de responsabilidad:\u00a0\u201cLas presuntas evasiones fueron llevadas a cabo por sociedades de las cuales yo no tengo ninguna participaci\u00f3n societaria\u201d.<\/p>\n<p>\u201cDebido a la inmensa cantidad de juicios laborales que tuve que afrontar y pagar, sumado a los bajos ingresos de la peluquer\u00eda, decid\u00ed dejar de explotar los diversos salones y ofrecer mis servicios como asesor en marketing, profesor de peinado y cortes de cabellos a diferentes empresas. Mi beneficio econ\u00f3mico era por ese asesoramiento.\u00a0A su vez le vend\u00ed a esas sociedades mi nombre (marca) para que promocionen sus comercios.\u00a0Por eso no es extra\u00f1o que en los tickets aparezca mi nombre\u201d, declar\u00f3 Giordano frente al magistrado.<\/p>\n<p>El juez no le crey\u00f3. B\u00e1sicamente, porque en el expediente hab\u00eda una serie de pruebas que contradec\u00edan a Giordano en varios aspectos.<\/p>\n<p>El magistrado construy\u00f3 su hip\u00f3tesis bas\u00e1ndonos en eso:\u00a0\u201cSin perjuicio de que Roberto Leonardo Giordano no integraba formalmente las empresas Unidor, Arimis, Big Bands y Nilamar era quien en los hechos dirig\u00eda y tomaba las decisiones inherentes al funcionamiento de aquellas, es decir era\u00a0el verdadero responsable de la explotaci\u00f3n de la cadena de peluquer\u00edas\u00a0y que los cargos directivos de tales empresas se encontrar\u00edan ocupados a t\u00edtulo formal por personas relacionadas con aquel\u201d.<\/p>\n<p>Fuente: Infobae<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roberto Giordano\u00a0fue condenado en la tarde de este mi\u00e9rcoles a\u00a03 a\u00f1os de prisi\u00f3n\u00a0luego de aceptar su culpabilidad en un\u00a0juicio abreviado\u00a0donde se lo acusaba de\u00a0insolvencia fraudulenta. Es decir, esconder bienes adrede para que no sean embargados por la justicia. La sentencia fue firmada en la tarde de hoy por el juez\u00a0Jorge Alejandro Zabala. Es v\u00e1lido recordar &hellip;<\/p>\n","protected":false},"author":1,"featured_media":5769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[198,88],"tags":[],"class_list":["post-5763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-judiciales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta | Al Dia Chaco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta | Al Dia Chaco\" \/>\n<meta property=\"og:description\" content=\"Roberto Giordano\u00a0fue condenado en la tarde de este mi\u00e9rcoles a\u00a03 a\u00f1os de prisi\u00f3n\u00a0luego de aceptar su culpabilidad en un\u00a0juicio abreviado\u00a0donde se lo acusaba de\u00a0insolvencia fraudulenta. Es decir, esconder bienes adrede para que no sean embargados por la justicia. La sentencia fue firmada en la tarde de hoy por el juez\u00a0Jorge Alejandro Zabala. Es v\u00e1lido recordar &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/\" \/>\n<meta property=\"og:site_name\" content=\"Al Dia Chaco\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-16T11:26:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-16T11:48:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/0000332010.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aldiachaco.com.ar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aldiachaco.com.ar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/\"},\"author\":{\"name\":\"aldiachaco.com.ar\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/person\\\/80113835e512ba580e79a945932487f5\"},\"headline\":\"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta\",\"datePublished\":\"2024-05-16T11:26:46+00:00\",\"dateModified\":\"2024-05-16T11:48:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/\"},\"wordCount\":789,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/0000332010.jpg\",\"articleSection\":[\"Actualidad\",\"Judiciales\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/\",\"name\":\"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta | Al Dia Chaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/0000332010.jpg\",\"datePublished\":\"2024-05-16T11:26:46+00:00\",\"dateModified\":\"2024-05-16T11:48:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/0000332010.jpg\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/0000332010.jpg\",\"width\":1500,\"height\":870},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2024\\\/05\\\/16\\\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\",\"name\":\"Al Dia Chaco\",\"description\":\"Noticias del Chaco y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\"},\"alternateName\":\"Al D\u00eda Chaco\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aldiachaco.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\",\"name\":\"Al Dia Chaco\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AL-DIA-CHACO-L@2x.png\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AL-DIA-CHACO-L@2x.png\",\"width\":232,\"height\":60,\"caption\":\"Al Dia Chaco\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/person\\\/80113835e512ba580e79a945932487f5\",\"name\":\"aldiachaco.com.ar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"caption\":\"aldiachaco.com.ar\"},\"sameAs\":[\"https:\\\/\\\/aldiachaco.com.ar\"],\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/author\\\/lime-camel-884546-hostingersite-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta | Al Dia Chaco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta | Al Dia Chaco","og_description":"Roberto Giordano\u00a0fue condenado en la tarde de este mi\u00e9rcoles a\u00a03 a\u00f1os de prisi\u00f3n\u00a0luego de aceptar su culpabilidad en un\u00a0juicio abreviado\u00a0donde se lo acusaba de\u00a0insolvencia fraudulenta. Es decir, esconder bienes adrede para que no sean embargados por la justicia. La sentencia fue firmada en la tarde de hoy por el juez\u00a0Jorge Alejandro Zabala. Es v\u00e1lido recordar &hellip;","og_url":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/","og_site_name":"Al Dia Chaco","article_published_time":"2024-05-16T11:26:46+00:00","article_modified_time":"2024-05-16T11:48:21+00:00","og_image":[{"width":1500,"height":870,"url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/0000332010.jpg","type":"image\/jpeg"}],"author":"aldiachaco.com.ar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aldiachaco.com.ar","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/#article","isPartOf":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/"},"author":{"name":"aldiachaco.com.ar","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/person\/80113835e512ba580e79a945932487f5"},"headline":"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta","datePublished":"2024-05-16T11:26:46+00:00","dateModified":"2024-05-16T11:48:21+00:00","mainEntityOfPage":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/"},"wordCount":789,"commentCount":0,"publisher":{"@id":"https:\/\/aldiachaco.com.ar\/#organization"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/#primaryimage"},"thumbnailUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/0000332010.jpg","articleSection":["Actualidad","Judiciales"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/","url":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/","name":"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta | Al Dia Chaco","isPartOf":{"@id":"https:\/\/aldiachaco.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/#primaryimage"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/#primaryimage"},"thumbnailUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/0000332010.jpg","datePublished":"2024-05-16T11:26:46+00:00","dateModified":"2024-05-16T11:48:21+00:00","breadcrumb":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/#primaryimage","url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/0000332010.jpg","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/0000332010.jpg","width":1500,"height":870},{"@type":"BreadcrumbList","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2024\/05\/16\/no-me-dentegan-soy-giordano-el-famoso-peluquero-fue-condenado-a-3-anos-de-prision-por-insolvencia-fraudulenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aldiachaco.com.ar\/"},{"@type":"ListItem","position":2,"name":"\u00a1No me dentegan, soy Giordano! El famoso peluquero fue condenado a 3 a\u00f1os de prisi\u00f3n por insolvencia fraudulenta"}]},{"@type":"WebSite","@id":"https:\/\/aldiachaco.com.ar\/#website","url":"https:\/\/aldiachaco.com.ar\/","name":"Al Dia Chaco","description":"Noticias del Chaco y el mundo","publisher":{"@id":"https:\/\/aldiachaco.com.ar\/#organization"},"alternateName":"Al D\u00eda Chaco","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aldiachaco.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/aldiachaco.com.ar\/#organization","name":"Al Dia Chaco","url":"https:\/\/aldiachaco.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2017\/11\/AL-DIA-CHACO-L@2x.png","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2017\/11\/AL-DIA-CHACO-L@2x.png","width":232,"height":60,"caption":"Al Dia Chaco"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/person\/80113835e512ba580e79a945932487f5","name":"aldiachaco.com.ar","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","url":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","caption":"aldiachaco.com.ar"},"sameAs":["https:\/\/aldiachaco.com.ar"],"url":"https:\/\/aldiachaco.com.ar\/index.php\/author\/lime-camel-884546-hostingersite-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2024\/05\/0000332010.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5763"}],"version-history":[{"count":0,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/media\/5769"}],"wp:attachment":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}