{"id":115911,"date":"2026-01-08T10:15:27","date_gmt":"2026-01-08T13:15:27","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=115911"},"modified":"2026-01-08T10:15:27","modified_gmt":"2026-01-08T13:15:27","slug":"buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura","status":"publish","type":"post","link":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/","title":{"rendered":"Buenos Aires: encontraron a una beba prematura abandonada entre la basura"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una beba reci\u00e9n nacida prematura fue hallada en un cesto de basura en la localidad bonaerense de San Mart\u00edn, aunque la menor se encuentra estable, contin\u00faa en Terapia Intensiva de Neonatolog\u00eda ya que naci\u00f3 de 36 semanas y el cord\u00f3n umbilical fue cortado de manera artesanal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el parte policial, la peque\u00f1a fue encontrada en la avenida Riobamba al 2300, sin ropa por lo que la trasladaron de manera inmediata por un m\u00f3vil policial al Hospital Municipal Dr. Diego Thompson donde la asisti\u00f3 la doctora Melina Pasarelli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La profesional de la salud inform\u00f3 que se trata de una reci\u00e9n nacida prematura, con aproximadamente 36 semanas de gestaci\u00f3n, con un peso de 1.890 gramos y cl\u00ednicamente estable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La misma m\u00e9dica consider\u00f3 que el parto fue natural y domiciliario, as\u00ed como estim\u00f3 el horario de nacimiento cerca de las 5.00 y all\u00ed se seccion\u00f3 el cord\u00f3n umbilical de forma artesanal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El personal m\u00e9dico nombr\u00f3 a la beba como &#8220;Ver\u00f3nica&#8221;, en reconocimiento a la teniente 1\u00b0 Ayala Ver\u00f3nica, que fue quien hall\u00f3 a la menor tras una alerta, en la madrugada de este mi\u00e9rcoles 7 de enero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El caso qued\u00f3 en manos de la UFI N\u00b0 03 del Departamento Judicial San Mart\u00edn, bajo la car\u00e1tula de abandono de persona y se realizar\u00e1 el relevamiento de c\u00e1maras de seguridad del sector.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una beba reci\u00e9n nacida prematura fue hallada en un cesto de basura en la localidad bonaerense de San Mart\u00edn, aunque la menor se encuentra estable, contin\u00faa en Terapia Intensiva de Neonatolog\u00eda ya que naci\u00f3 de 36 semanas y el cord\u00f3n umbilical fue cortado de manera artesanal. Seg\u00fan el parte policial, la peque\u00f1a fue encontrada en &hellip;<\/p>\n","protected":false},"author":1,"featured_media":115912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[86],"tags":[],"class_list":["post-115911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Buenos Aires: encontraron a una beba prematura abandonada entre la basura | Al Dia Chaco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buenos Aires: encontraron a una beba prematura abandonada entre la basura | Al Dia Chaco\" \/>\n<meta property=\"og:description\" content=\"Una beba reci\u00e9n nacida prematura fue hallada en un cesto de basura en la localidad bonaerense de San Mart\u00edn, aunque la menor se encuentra estable, contin\u00faa en Terapia Intensiva de Neonatolog\u00eda ya que naci\u00f3 de 36 semanas y el cord\u00f3n umbilical fue cortado de manera artesanal. Seg\u00fan el parte policial, la peque\u00f1a fue encontrada en &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/\" \/>\n<meta property=\"og:site_name\" content=\"Al Dia Chaco\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-08T13:15:27+00:00\" \/>\n<meta name=\"author\" content=\"aldiachaco.com.ar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aldiachaco.com.ar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/\"},\"author\":{\"name\":\"aldiachaco.com.ar\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/person\\\/80113835e512ba580e79a945932487f5\"},\"headline\":\"Buenos Aires: encontraron a una beba prematura abandonada entre la basura\",\"datePublished\":\"2026-01-08T13:15:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/\"},\"wordCount\":240,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/BEbe-abandonada.jpeg\",\"articleSection\":[\"Policiales\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/\",\"name\":\"Buenos Aires: encontraron a una beba prematura abandonada entre la basura | Al Dia Chaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/BEbe-abandonada.jpeg\",\"datePublished\":\"2026-01-08T13:15:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/BEbe-abandonada.jpeg\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/BEbe-abandonada.jpeg\",\"width\":1271,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/2026\\\/01\\\/08\\\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buenos Aires: encontraron a una beba prematura abandonada entre la basura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\",\"name\":\"Al Dia Chaco\",\"description\":\"Noticias del Chaco y el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\"},\"alternateName\":\"Al D\u00eda Chaco\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aldiachaco.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#organization\",\"name\":\"Al Dia Chaco\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AL-DIA-CHACO-L@2x.png\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AL-DIA-CHACO-L@2x.png\",\"width\":232,\"height\":60,\"caption\":\"Al Dia Chaco\"},\"image\":{\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/#\\\/schema\\\/person\\\/80113835e512ba580e79a945932487f5\",\"name\":\"aldiachaco.com.ar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"contentUrl\":\"https:\\\/\\\/aldiachaco.com.ar\\\/wp-content\\\/litespeed\\\/avatar\\\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223\",\"caption\":\"aldiachaco.com.ar\"},\"sameAs\":[\"https:\\\/\\\/aldiachaco.com.ar\"],\"url\":\"https:\\\/\\\/aldiachaco.com.ar\\\/index.php\\\/author\\\/lime-camel-884546-hostingersite-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buenos Aires: encontraron a una beba prematura abandonada entre la basura | Al Dia Chaco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/","og_locale":"es_ES","og_type":"article","og_title":"Buenos Aires: encontraron a una beba prematura abandonada entre la basura | Al Dia Chaco","og_description":"Una beba reci\u00e9n nacida prematura fue hallada en un cesto de basura en la localidad bonaerense de San Mart\u00edn, aunque la menor se encuentra estable, contin\u00faa en Terapia Intensiva de Neonatolog\u00eda ya que naci\u00f3 de 36 semanas y el cord\u00f3n umbilical fue cortado de manera artesanal. Seg\u00fan el parte policial, la peque\u00f1a fue encontrada en &hellip;","og_url":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/","og_site_name":"Al Dia Chaco","article_published_time":"2026-01-08T13:15:27+00:00","author":"aldiachaco.com.ar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aldiachaco.com.ar","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/#article","isPartOf":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/"},"author":{"name":"aldiachaco.com.ar","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/person\/80113835e512ba580e79a945932487f5"},"headline":"Buenos Aires: encontraron a una beba prematura abandonada entre la basura","datePublished":"2026-01-08T13:15:27+00:00","mainEntityOfPage":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/"},"wordCount":240,"commentCount":0,"publisher":{"@id":"https:\/\/aldiachaco.com.ar\/#organization"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/#primaryimage"},"thumbnailUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2026\/01\/BEbe-abandonada.jpeg","articleSection":["Policiales"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/","url":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/","name":"Buenos Aires: encontraron a una beba prematura abandonada entre la basura | Al Dia Chaco","isPartOf":{"@id":"https:\/\/aldiachaco.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/#primaryimage"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/#primaryimage"},"thumbnailUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2026\/01\/BEbe-abandonada.jpeg","datePublished":"2026-01-08T13:15:27+00:00","breadcrumb":{"@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/#primaryimage","url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2026\/01\/BEbe-abandonada.jpeg","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2026\/01\/BEbe-abandonada.jpeg","width":1271,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/aldiachaco.com.ar\/index.php\/2026\/01\/08\/buenos-aires-encontraron-a-una-beba-prematura-abandonada-entre-la-basura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aldiachaco.com.ar\/"},{"@type":"ListItem","position":2,"name":"Buenos Aires: encontraron a una beba prematura abandonada entre la basura"}]},{"@type":"WebSite","@id":"https:\/\/aldiachaco.com.ar\/#website","url":"https:\/\/aldiachaco.com.ar\/","name":"Al Dia Chaco","description":"Noticias del Chaco y el mundo","publisher":{"@id":"https:\/\/aldiachaco.com.ar\/#organization"},"alternateName":"Al D\u00eda Chaco","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aldiachaco.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/aldiachaco.com.ar\/#organization","name":"Al Dia Chaco","url":"https:\/\/aldiachaco.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2017\/11\/AL-DIA-CHACO-L@2x.png","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2017\/11\/AL-DIA-CHACO-L@2x.png","width":232,"height":60,"caption":"Al Dia Chaco"},"image":{"@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aldiachaco.com.ar\/#\/schema\/person\/80113835e512ba580e79a945932487f5","name":"aldiachaco.com.ar","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","url":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","contentUrl":"https:\/\/aldiachaco.com.ar\/wp-content\/litespeed\/avatar\/a7c4ebc5454089d3fd4ef6b87fdd073a.jpg?ver=1783522223","caption":"aldiachaco.com.ar"},"sameAs":["https:\/\/aldiachaco.com.ar"],"url":"https:\/\/aldiachaco.com.ar\/index.php\/author\/lime-camel-884546-hostingersite-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/aldiachaco.com.ar\/wp-content\/uploads\/2026\/01\/BEbe-abandonada.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/115911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=115911"}],"version-history":[{"count":0,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/115911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/media\/115912"}],"wp:attachment":[{"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=115911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=115911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aldiachaco.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=115911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}